{"id":25865948,"date":"2026-07-20T09:36:39","date_gmt":"2026-07-20T13:36:39","guid":{"rendered":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/"},"modified":"2026-09-02T05:06:09","modified_gmt":"2026-09-02T09:06:09","slug":"pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f","status":"publish","type":"product","link":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/","title":{"rendered":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F"},"content":{"rendered":"<p>-6.25 inches tall<br \/>\n-Rig style dab rig<br \/>\n-Circ percolator<br \/>\n-Chill frogs &#038; mushrooms decal design<br \/>\n-Angled mouthpiece<br \/>\n-Borosilicate glass<br \/>\n-Black Pulsar logo<br \/>\n-Includes 14mm male quartz banger<\/p>\n<p>The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and a tilted neck for user comfort. The circular percolator ensures a smooth and well-cooled hit. Standing 6.25 inches (15.9cm) tall, it is crafted with quality borosilicate glass, making the pipe easy to clean for long term use. Includes a 14mm male flat top quartz banger.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &#038; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and [&hellip;]<\/p>\n","protected":false},"featured_media":25864148,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[4386],"product_cat":[4297,4307],"product_tag":[],"class_list":["post-25865948","product","type-product","status-publish","has-post-thumbnail","product_brand-pulsar","product_cat-gear","product_cat-paraphernalia","pa_brand-type-national-favorites","pa_brands-pulsar","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &amp; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"BoomX Cannabis | Recreational Dispensary\" \/>\n\t\t<meta property=\"og:type\" content=\"product\" \/>\n\t\t<meta property=\"og:title\" content=\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis\" \/>\n\t\t<meta property=\"og:description\" content=\"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &amp; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis\" \/>\n\t\t<meta name=\"twitter:description\" content=\"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &amp; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-two\\\/#listItem\",\"position\":1,\"name\":\"Shop Two\",\"item\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-two\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/brand\\\/pulsar\\\/#listItem\",\"name\":\"Pulsar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/brand\\\/pulsar\\\/#listItem\",\"position\":2,\"name\":\"Pulsar\",\"item\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/brand\\\/pulsar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#listItem\",\"name\":\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-two\\\/#listItem\",\"name\":\"Shop Two\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#listItem\",\"position\":3,\"name\":\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/brand\\\/pulsar\\\/#listItem\",\"name\":\"Pulsar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#organization\",\"name\":\"BoomX Cannabis\",\"description\":\"Recreational Dispensary\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/\",\"telephone\":\"+19787334677\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/boomx\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/BOOM-X-color-logo-square.jpg\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#organizationLogo\"},\"address\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"114 Lancaster Road\",\"postalCode\":\"01464\",\"addressLocality\":\"Shirley\",\"addressRegion\":\"MA\",\"addressCountry\":\"US\"}},{\"@type\":\"Product\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#wooCommerceProduct\",\"name\":\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\\\" | 14mm F\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/\",\"brand\":{\"@type\":\"Brand\",\"name\":\"Pulsar\"},\"sku\":\"4703983\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#productImage\",\"width\":1000,\"height\":1000},\"offers\":{\"@type\":\"Offer\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#wooCommerceOffer\",\"price\":35,\"priceCurrency\":\"USD\",\"category\":\"Gear\",\"availability\":\"https:\\\/\\\/schema.org\\\/InStock\",\"priceSpecification\":{\"@type\":\"PriceSpecification\",\"price\":35,\"priceCurrency\":\"USD\",\"valueAddedTaxIncluded\":false},\"seller\":{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#organization\"}}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#webpage\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/\",\"name\":\"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\\u2033 | 14mm F | BoomX Cannabis\",\"description\":\"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs & mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#mainImage\",\"width\":1000,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/shop-cannabis\\\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\\\/#mainImage\"},\"datePublished\":\"2026-07-20T09:36:39-04:00\",\"dateModified\":\"2026-09-02T05:06:09-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#website\",\"url\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/\",\"name\":\"BoomX Cannabis Co.\",\"alternateName\":\"BoomX Cannabis\",\"description\":\"Recreational Dispensary\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/seo47.serpcom.com\\\/cannabis-dispensary-shirley-ma\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis<\/title>\n\n","aioseo_head_json":{"title":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis","description":"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs & mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and","canonical_url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/","robots":"noindex, nofollow, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-two\/#listItem","position":1,"name":"Shop Two","item":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-two\/","nextItem":{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/#listItem","name":"Pulsar"}},{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/#listItem","position":2,"name":"Pulsar","item":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#listItem","name":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F"},"previousItem":{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-two\/#listItem","name":"Shop Two"}},{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#listItem","position":3,"name":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F","previousItem":{"@type":"ListItem","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/#listItem","name":"Pulsar"}}]},{"@type":"Organization","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#organization","name":"BoomX Cannabis","description":"Recreational Dispensary","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/","telephone":"+19787334677","logo":{"@type":"ImageObject","url":"https:\/\/seo47.serpcom.com\/boomx\/wp-content\/uploads\/sites\/2\/2025\/12\/BOOM-X-color-logo-square.jpg","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#organizationLogo"},"image":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#organizationLogo"},"address":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#postaladdress","@type":"PostalAddress","streetAddress":"114 Lancaster Road","postalCode":"01464","addressLocality":"Shirley","addressRegion":"MA","addressCountry":"US"}},{"@type":"Product","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#wooCommerceProduct","name":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\" | 14mm F","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/","brand":{"@type":"Brand","name":"Pulsar"},"sku":"4703983","image":{"@type":"ImageObject","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#productImage","width":1000,"height":1000},"offers":{"@type":"Offer","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#wooCommerceOffer","price":35,"priceCurrency":"USD","category":"Gear","availability":"https:\/\/schema.org\/InStock","priceSpecification":{"@type":"PriceSpecification","price":35,"priceCurrency":"USD","valueAddedTaxIncluded":false},"seller":{"@type":"Organization","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#organization"}}},{"@type":"WebPage","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#webpage","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/","name":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis","description":"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs & mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#website"},"breadcrumb":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#mainImage","width":1000,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/#mainImage"},"datePublished":"2026-07-20T09:36:39-04:00","dateModified":"2026-09-02T05:06:09-04:00"},{"@type":"WebSite","@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#website","url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/","name":"BoomX Cannabis Co.","alternateName":"BoomX Cannabis","description":"Recreational Dispensary","inLanguage":"en-US","publisher":{"@id":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/#organization"}}]},"og:locale":"en_US","og:site_name":"BoomX Cannabis | Recreational Dispensary","og:type":"product","og:title":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis","og:description":"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &amp; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and","og:url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/","og:image":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg","og:image:secure_url":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg","og:image:width":1000,"og:image:height":1000,"twitter:card":"summary_large_image","twitter:title":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F | BoomX Cannabis","twitter:description":"-6.25 inches tall -Rig style dab rig -Circ percolator -Chill frogs &amp; mushrooms decal design -Angled mouthpiece -Borosilicate glass -Black Pulsar logo -Includes 14mm male quartz banger The Froggy Fun Guy Glass Dab Rig from Pulsar has decal designs of chill frogs on and under mushrooms on both sides, a solid base for stability, and","twitter:image":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-content\/uploads\/sites\/2\/2026\/07\/27407ea4-8030-42a2-9e0d-9850738ea860.jpeg"},"aioseo_meta_data":{"post_id":"25865948","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-07-20 13:36:39","updated":"2026-09-02 09:06:09","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-two\/\" title=\"Shop Two\">Shop Two<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/\" title=\"Pulsar\">Pulsar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tPulsar Froggy Fun Guy Glass Dab Rig | 6.25\u2033 | 14mm F\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Shop Two","link":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-two\/"},{"label":"Pulsar","link":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/brand\/pulsar\/"},{"label":"Pulsar Froggy Fun Guy Glass Dab Rig | 6.25&#8243; | 14mm F","link":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/shop-cannabis\/pulsar-froggy-fun-guy-glass-dab-rig-6-25-14mm-f\/"}],"_links":{"self":[{"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/product\/25865948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/comments?post=25865948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/media\/25864148"}],"wp:attachment":[{"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/media?parent=25865948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/product_brand?post=25865948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/product_cat?post=25865948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seo47.serpcom.com\/cannabis-dispensary-shirley-ma\/wp-json\/wp\/v2\/product_tag?post=25865948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}